{"id":880,"count":1,"description":"","link":"https:\/\/site.extension.uga.edu\/greenway\/tag\/teaching\/","name":"teaching","slug":"teaching","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/site.extension.uga.edu\/greenway\/wp-json\/wp\/v2\/tags\/880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.extension.uga.edu\/greenway\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/site.extension.uga.edu\/greenway\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/site.extension.uga.edu\/greenway\/wp-json\/wp\/v2\/posts?tags=880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}